{"id":1454,"date":"2024-08-22T17:20:19","date_gmt":"2024-08-22T22:20:19","guid":{"rendered":"https:\/\/www.dacgroup.com\/?post_type=services&#038;p=1454"},"modified":"2026-02-10T12:25:51","modified_gmt":"2026-02-10T17:25:51","slug":"medias-traditionnels","status":"publish","type":"services","link":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/","title":{"rendered":"M\u00e9dias traditionnels"},"content":{"rendered":"\n\n    <style>\n        #hero-internal {\n            background-image: url('https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/hero-d-full-funnel-traditional-offline.png');\n            height: 720px !important;\n        }\n\n                @media (min-width: 2000px) {\n            #hero-internal {\n                background-image: url('https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/hero-d-paid-media-traditional-offline-2.png');\n                height: 720px !important;\n            }\n        }\n        \n\n                @media screen and (max-width: 991px) {\n            #hero-internal {\n                background-image: url('https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/hero-m-full-funnel-traditional-offline.png');\n                height: 500px !important;\n            }\n        }\n\n            <\/style>\n\n\n<section id=\"hero-internal\" class=\"noWords background-image\"\n         data-desktoph=\"720px\" data-mobileh=\"500px\">\n\n            <nav class=\"breadcrumb container max-1448 padding60 desktop-only \">\n            <a href=\"https:\/\/www.dacgroup.com\/fr\/\">DAC<\/a><img decoding=\"async\" src=\"https:\/\/www.dacgroup.com\/wp-content\/themes\/dac\/img\/chevron-right-white.svg\" alt=\"\" aria-hidden=\"true\"><a class=\"text-capitalize\" href=\"https:\/\/www.dacgroup.com\/fr\/services\/\">Services<\/a><img decoding=\"async\" src=\"https:\/\/www.dacgroup.com\/wp-content\/themes\/dac\/img\/chevron-right-white.svg\" alt=\"\" aria-hidden=\"true\"><a class=\"text-capitalize\" href=\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/\">M\u00e9dias Payants<\/a>        <\/nav>\n    \n    \n    <div class=\"container max-1448 padding60 hero-internal-content-block\"\n         style=\"text-align:left;align-items:start\">\n\n                            <h1 style=\"color:#ffffff;\">\n                Des m\u00e9dias traditionnels performants            <\/h1>\n        \n                    <div class=\"description\" style=\"color:#ffffff;\">\n                <p>Ayant commenc\u00e9 comme unn Annonceur d\u2019impression d\u2019entreprise \u00e0 local il y a plus de 50 ans, nos capacit\u00e9s traditionnelles et hors ligne sont incomparables et enti\u00e8rement optimis\u00e9es pour le 21e si\u00e8cle.<\/p>            <\/div>\n                    \n        <div class=\"cta-container-row\">\n           \n                        <div class=\"  \" data-role=\"cta\">\n\n                                                <a role=\"button\" href='https:\/\/www.dacgroup.com\/fr\/contactez-nous\/' class=\"btn_primary-filled_white_hand  \"  >\n                        \n                        <div>PARLONS M\u00c9DIAS TRADITIONNELS <\/div>\n\n                        \n                                \n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\">\n                                            <g clip-path=\"url(#clip0_2625_299)\">\n                                                <rect width=\"24\" height=\"24\" \/>\n                                                <path d=\"M21.7073 14.8912C21.6071 15.0021 21.4862 15.092 21.3517 15.1553C19.9543 15.7739 16.2814 17.4092 12.3524 19.2435C10.9313 19.9218 9.44711 20.454 7.92204 20.8317C6.90068 21.072 5.83695 21.0548 4.82359 20.7811C3.81023 20.5073 2.87806 19.9857 2.10855 19.2616C1.36839 18.5696 0.795336 17.7128 0.434438 16.7583C0.0735402 15.8038 -0.0654262 14.7769 0.0285021 13.7588L1.0952 2.9341C1.14142 2.46498 1.3752 2.03566 1.74173 1.74683C2.10826 1.4583 2.57494 1.3353 3.03302 1.40705C3.45703 1.47428 3.83986 1.70311 4.10416 2.04711C4.36817 2.39111 4.4938 2.82466 4.45528 3.2594L4.01794 8.10736C3.99364 8.43387 4.09883 8.75676 4.31039 9.00368C4.52195 9.2506 4.8221 9.40074 5.1433 9.42064C5.46449 9.44054 5.78035 9.32839 6.01976 9.10951L15.5489 0.325307C15.7738 0.116073 16.0674 0 16.372 0C16.6766 0 16.9706 0.116073 17.1952 0.325307C17.4438 0.556248 17.5875 0.881556 17.5922 1.22435C17.5969 1.56684 17.4621 1.89637 17.22 2.13424L11.8439 7.41634C11.7168 7.54357 11.6602 7.72687 11.6928 7.90536C11.7254 8.08384 11.843 8.23428 12.0066 8.30634C12.1701 8.3787 12.3586 8.36392 12.5088 8.26624L19.325 3.72943C19.642 3.55275 20.0249 3.54763 20.3463 3.71586C20.6678 3.88439 20.8859 4.20427 20.9286 4.56968C20.9713 4.93508 20.8329 5.29808 20.5591 5.53836L13.9385 10.4189C13.8241 10.5045 13.7394 10.6251 13.6973 10.7632C13.6552 10.9013 13.6576 11.0493 13.7041 11.1859C13.7663 11.3692 13.9038 11.516 14.081 11.5874C14.2603 11.6595 14.4612 11.649 14.6321 11.5585L20.3212 8.55205C20.6678 8.36814 21.0839 8.38322 21.4166 8.59185C21.7493 8.80078 21.9494 9.17222 21.9434 9.56958C21.9375 9.96724 21.7265 10.3323 21.3879 10.531L14.849 14.4275C14.7237 14.5083 14.6461 14.647 14.6413 14.7977C14.6366 14.9485 14.7053 15.092 14.8253 15.1806C14.945 15.2695 15.1006 15.2922 15.2401 15.2412L20.4989 13.103C20.7766 12.9906 21.0874 12.9984 21.3594 13.1247C21.6293 13.2456 21.8376 13.4748 21.9354 13.7579C22.0033 13.9496 22.0181 14.1567 21.9778 14.3566C21.9375 14.5565 21.8442 14.741 21.7079 14.8903L21.7073 14.8912Z\" \/>\n                                            <\/g>\n                                            <defs>\n                                                <clipPath id=\"clip0_2625_299\">\n                                                    <rect width=\"24\" height=\"24\" \/>\n                                                <\/clipPath>\n                                            <\/defs>\n                                        <\/svg>\n\n                                \n\n                        \n                                                    <\/a>\n                    \n                <\/div>\n                                <\/div>\n \n    <\/div>\n<\/section>\n\n\n    <div class=\"responsive-hero-footer mobile-only\">\n                    <nav class=\"breadcrumb container max-1448 padding60 mobile-only\">\n                <a href=\"https:\/\/www.dacgroup.com\/fr\/\">DAC<\/a><img decoding=\"async\" src=\"https:\/\/www.dacgroup.com\/wp-content\/themes\/dac\/img\/chevron-right-white.svg\" alt=\"\" aria-hidden=\"true\"><a class=\"text-capitalize\" href=\"https:\/\/www.dacgroup.com\/fr\/services\/\">Services<\/a><img decoding=\"async\" src=\"https:\/\/www.dacgroup.com\/wp-content\/themes\/dac\/img\/chevron-right-white.svg\" alt=\"\" aria-hidden=\"true\"><a class=\"text-capitalize\" href=\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/\">M\u00e9dias Payants<\/a>            <\/nav>\n        \n        \n                    <h1 style=\"color:#ffffff; \" class=\"mt-0\">\n                Des m\u00e9dias traditionnels performants            <\/h1>\n        \n                    <div class=\"description\" style=\"color:#ffffff;\">\n                <p>Ayant commenc\u00e9 comme unn Annonceur d\u2019impression d\u2019entreprise \u00e0 local il y a plus de 50 ans, nos capacit\u00e9s traditionnelles et hors ligne sont incomparables et enti\u00e8rement optimis\u00e9es pour le 21e si\u00e8cle.<\/p>            <\/div>\n        \n\n        <div class=\"cta-container-row mobile\">\n           \n                        <div class=\"  \" data-role=\"cta\">\n\n                                                <a role=\"button\" href='https:\/\/www.dacgroup.com\/fr\/contactez-nous\/' class=\"btn_primary-filled_white_hand  \"  >\n                        \n                        <div>PARLONS M\u00c9DIAS TRADITIONNELS <\/div>\n\n                        \n                                \n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"24\" height=\"24\" viewBox=\"0 0 24 24\">\n                                            <g clip-path=\"url(#clip0_2625_299)\">\n                                                <rect width=\"24\" height=\"24\" \/>\n                                                <path d=\"M21.7073 14.8912C21.6071 15.0021 21.4862 15.092 21.3517 15.1553C19.9543 15.7739 16.2814 17.4092 12.3524 19.2435C10.9313 19.9218 9.44711 20.454 7.92204 20.8317C6.90068 21.072 5.83695 21.0548 4.82359 20.7811C3.81023 20.5073 2.87806 19.9857 2.10855 19.2616C1.36839 18.5696 0.795336 17.7128 0.434438 16.7583C0.0735402 15.8038 -0.0654262 14.7769 0.0285021 13.7588L1.0952 2.9341C1.14142 2.46498 1.3752 2.03566 1.74173 1.74683C2.10826 1.4583 2.57494 1.3353 3.03302 1.40705C3.45703 1.47428 3.83986 1.70311 4.10416 2.04711C4.36817 2.39111 4.4938 2.82466 4.45528 3.2594L4.01794 8.10736C3.99364 8.43387 4.09883 8.75676 4.31039 9.00368C4.52195 9.2506 4.8221 9.40074 5.1433 9.42064C5.46449 9.44054 5.78035 9.32839 6.01976 9.10951L15.5489 0.325307C15.7738 0.116073 16.0674 0 16.372 0C16.6766 0 16.9706 0.116073 17.1952 0.325307C17.4438 0.556248 17.5875 0.881556 17.5922 1.22435C17.5969 1.56684 17.4621 1.89637 17.22 2.13424L11.8439 7.41634C11.7168 7.54357 11.6602 7.72687 11.6928 7.90536C11.7254 8.08384 11.843 8.23428 12.0066 8.30634C12.1701 8.3787 12.3586 8.36392 12.5088 8.26624L19.325 3.72943C19.642 3.55275 20.0249 3.54763 20.3463 3.71586C20.6678 3.88439 20.8859 4.20427 20.9286 4.56968C20.9713 4.93508 20.8329 5.29808 20.5591 5.53836L13.9385 10.4189C13.8241 10.5045 13.7394 10.6251 13.6973 10.7632C13.6552 10.9013 13.6576 11.0493 13.7041 11.1859C13.7663 11.3692 13.9038 11.516 14.081 11.5874C14.2603 11.6595 14.4612 11.649 14.6321 11.5585L20.3212 8.55205C20.6678 8.36814 21.0839 8.38322 21.4166 8.59185C21.7493 8.80078 21.9494 9.17222 21.9434 9.56958C21.9375 9.96724 21.7265 10.3323 21.3879 10.531L14.849 14.4275C14.7237 14.5083 14.6461 14.647 14.6413 14.7977C14.6366 14.9485 14.7053 15.092 14.8253 15.1806C14.945 15.2695 15.1006 15.2922 15.2401 15.2412L20.4989 13.103C20.7766 12.9906 21.0874 12.9984 21.3594 13.1247C21.6293 13.2456 21.8376 13.4748 21.9354 13.7579C22.0033 13.9496 22.0181 14.1567 21.9778 14.3566C21.9375 14.5565 21.8442 14.741 21.7079 14.8903L21.7073 14.8912Z\" \/>\n                                            <\/g>\n                                            <defs>\n                                                <clipPath id=\"clip0_2625_299\">\n                                                    <rect width=\"24\" height=\"24\" \/>\n                                                <\/clipPath>\n                                            <\/defs>\n                                        <\/svg>\n\n                                \n\n                        \n                                                    <\/a>\n                    \n                <\/div>\n            \n                        <\/div>\n    <\/div>\n\n\n\n    <style>\n        :root {\n            --dots-color: #00aae7;\n        }\n\n        .services-carousel__title strong,\n        [data-theme=\"dark\"] [data-id=\"6a04f69061045\"]\n        {\n            color:#00aae7 !important;\n        }\n    <\/style>\n    \n\n\n<section id=\"services-carousel\" class=\"\">\n\n    <div class=\"services-carousel  black large\">\n\n        <div class=\"container wrapper max-1448 padding60\">\n            \n            <div class=\"d-flex flex-column text-container\">\n                                    <h2 class=\"services-carousel__title  \">\n                        Faites <strong>progresser <\/strong>vos m\u00e9dias avec une agence prim\u00e9e                    <\/h2>\n                    \n\n                \n                            <\/div>\n\n            <div class=\"services-carousel__items carousel\" data-theme=\"dark\">\n\n                <div class=\"carousel-wrapper owl-carousel owl-theme\">\n                                                                        <div class=\"services-carousel__item item\">\n                                                                    <div class=\"services-carousel__image\" >\n                                                <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-forrester.jpg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-forrester.jpg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-forrester.jpg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-forrester.jpg\"\n                alt=\"Forrester\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                                <\/div>\n                                                                <h3  class=\"services-carousel__item-title \" data-id=\"6a04f69061045\" style=\"text-align: center\">Rapport de Forrester<\/h3>\n                                <p class=\"services-carousel__item-description\" style=\"text-align: center\">DAC est reconnu pour son offre unique destin\u00e9e aux marques multi-sites. <\/p>\n                            <\/div>\n                                                    <div class=\"services-carousel__item item\">\n                                                                    <div class=\"services-carousel__image\" >\n                                                <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-globee-awards.jpg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-globee-awards.jpg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-globee-awards.jpg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-globee-awards.jpg\"\n                alt=\"globee award logo\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                                <\/div>\n                                                                <h3  class=\"services-carousel__item-title \" data-id=\"6a04f69061045\" style=\"text-align: center\">Globee Awards<\/h3>\n                                <p class=\"services-carousel__item-description\" style=\"text-align: center\">Le prix du d\u00e9partement de l\u2019ann\u00e9e dirig\u00e9 par une femme a \u00e9t\u00e9 d\u00e9cern\u00e9 \u00e0 Jenna Watson, vice-pr\u00e9sidente principale des m\u00e9dias chez DAC. <\/p>\n                            <\/div>\n                                                    <div class=\"services-carousel__item item\">\n                                                                    <div class=\"services-carousel__image\" >\n                                                <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-search-engine-land.jpg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-search-engine-land.jpg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-search-engine-land.jpg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/award-search-engine-land.jpg\"\n                alt=\"Search engine land award logo\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                                <\/div>\n                                                                <h3  class=\"services-carousel__item-title \" data-id=\"6a04f69061045\" style=\"text-align: center\">Search Engine Land Awards<\/h3>\n                                <p class=\"services-carousel__item-description\" style=\"text-align: center\">Meilleure initiative de marketing de recherche locale &#8211; PPC avec notre client The Fresh Market. <\/p>\n                            <\/div>\n                                                            <\/div>\n\n            <\/div>\n\n                    <\/div>\n\n    <\/div>\n\n<\/section>\n\n\n<section id=\"services\" class=\"text-accordion-block\">\n    <div class=\"overlay\"><\/div>\n\n    <div class=\"container max-1448 padding60\">\n        \n        <div>\n            <h2>Le pouvoir de donner vie \u00e0 votre marque<\/h2>\n\n                        <div class=\"large-description\"><p data-pm-slice=\"1 1 []\">Nous renfor\u00e7ons et acc\u00e9l\u00e9rons m\u00eame les strat\u00e9gies digitales les plus complexes, des campagnes nationales aux placements locaux, \u00e0 travers des publicit\u00e9s imprim\u00e9es, TV, radio et en affichage ext\u00e9rieur (OOH). Ce storytelling \u00e0 fort impact permet \u00e0 votre marque de se rapprocher de vos audiences dans leurs quotidiens et de cr\u00e9er des connexions significatives.<\/p><\/div>\n\n                        <a href=\"https:\/\/www.dacgroup.com\/fr\/contactez-nous\/\" class=\"btn_primary-filled_white_hand\" >\n                <div>PARLONS M\u00c9DIAS TRADITIONNELS<\/div>\n                <svg width=\"24\" height=\"16\" viewBox=\"0 0 24 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                    <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"#171616\"><\/path>\n                    <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"><\/path>\n                    <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"#171616\"><\/path>\n                <\/svg>\n            <\/a>\n                    <\/div>\n\n        <div>\n            <div class=\"accordion services-loop\" id=\"services-home-accordion\">\n                                    <div class=\"accordion-item\">\n                        <h3 class=\"accordion-header\" id=\"heading-1\">\n                            <button class=\"pe-3 accordion-button \" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-1\" aria-expanded=\"true\" aria-controls=\"collapse-1\">\n                                <span class=\"d-inline-block\" style=\"padding-right:16px;\">\n                                    Strat\u00e9gie et ex\u00e9cution OOH                                 <\/span>\n                            <\/button>\n                        <\/h3>\n                        <div id=\"collapse-1\" class=\"accordion-collapse show\" aria-labelledby=\"heading-1\" data-bs-parent=\"#services-home-accordion\">\n                            <div class=\"accordion-body ps-3 ms-1 ps-lg-0 ms-lg-0\">\n                                DAC \u00e9labore des strat\u00e9gies OOH qui captivent et convertissent, riches de notre h\u00e9ritage en publicit\u00e9 imprim\u00e9e. Notre expertise et nos partenariats dans la publicit\u00e9 ext\u00e9rieure se d\u00e9ploient sur les panneaux d\u2019affichage, les abris de transport en commun et plus encore, vous donnant toutes les occasions d\u2019amplifier le message de votre marque aux bons publics au bon moment et de g\u00e9n\u00e9rer des r\u00e9sultats percutants dans les zones \u00e0 fort trafic.                              <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"accordion-item\">\n                        <h3 class=\"accordion-header\" id=\"heading-2\">\n                            <button class=\"pe-3 accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-2\" aria-expanded=\"false\" aria-controls=\"collapse-2\">\n                                <span class=\"d-inline-block\" style=\"padding-right:16px;\">\n                                    Plans pour les m\u00e9dias imprim\u00e9s                                 <\/span>\n                            <\/button>\n                        <\/h3>\n                        <div id=\"collapse-2\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-2\" data-bs-parent=\"#services-home-accordion\">\n                            <div class=\"accordion-body ps-3 ms-1 ps-lg-0 ms-lg-0\">\n                                Fort d&#8217;une exp\u00e9rience de l\u2019impression qui remonte \u00e0 1972, chaque plan de m\u00e9dias imprim\u00e9s de DAC est le r\u00e9sultat direct de notre expertise in\u00e9gal\u00e9e. Nous tirons parti de notre connaissance approfondie de l\u2019industrie pour cr\u00e9er des campagnes d\u2019impression cibl\u00e9es qui r\u00e9sonnent avec vos publics, avec des placements strat\u00e9giques garantissant une visibilit\u00e9 et un engagement maximaux.                              <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"accordion-item\">\n                        <h3 class=\"accordion-header\" id=\"heading-3\">\n                            <button class=\"pe-3 accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-3\" aria-expanded=\"false\" aria-controls=\"collapse-3\">\n                                <span class=\"d-inline-block\" style=\"padding-right:16px;\">\n                                    Publicit\u00e9 t\u00e9l\u00e9vis\u00e9e                                  <\/span>\n                            <\/button>\n                        <\/h3>\n                        <div id=\"collapse-3\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-3\" data-bs-parent=\"#services-home-accordion\">\n                            <div class=\"accordion-body ps-3 ms-1 ps-lg-0 ms-lg-0\">\n                                La t\u00e9l\u00e9vision reste un moyen puissant pour raconter l&#8217;histoire de votre marque, et notre exp\u00e9rience de grande envergure garantit que votre message fasse son chemin \u00e0 travers la multitude de messages. Nous d\u00e9veloppons et ex\u00e9cutons des campagnes publicitaires t\u00e9l\u00e9vis\u00e9es , traditionnelles et non lin\u00e9aires, qui sont strat\u00e9giquement optimis\u00e9es pour maximiser la port\u00e9e, tirer profit de vos donn\u00e9es d\u00e9mographiques et g\u00e9n\u00e9rer des r\u00e9sultats aujourd&#8217;hui et demain.                              <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"accordion-item\">\n                        <h3 class=\"accordion-header\" id=\"heading-4\">\n                            <button class=\"pe-3 accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-4\" aria-expanded=\"false\" aria-controls=\"collapse-4\">\n                                <span class=\"d-inline-block\" style=\"padding-right:16px;\">\n                                    Publicit\u00e9 radio et audio                                  <\/span>\n                            <\/button>\n                        <\/h3>\n                        <div id=\"collapse-4\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-4\" data-bs-parent=\"#services-home-accordion\">\n                            <div class=\"accordion-body ps-3 ms-1 ps-lg-0 ms-lg-0\">\n                                La publicit\u00e9 \u00e0 la radio et audio offre une occasion unique de se connecter avec des audiences en d\u00e9placement, et nos campagnes sur mesure exploitent ce potentiel pour transmettre votre message avec clart\u00e9 et impact. Qu\u2019il s\u2019agisse de spots radio traditionnels ou de publicit\u00e9s audio num\u00e9riques , nationales ou locales , nous nous assurons que votre marque est entendue haut et fort.                              <\/div>\n                        <\/div>\n                    <\/div>\n                                    <div class=\"accordion-item\">\n                        <h3 class=\"accordion-header\" id=\"heading-5\">\n                            <button class=\"pe-3 accordion-button collapsed\" type=\"button\" data-bs-toggle=\"collapse\" data-bs-target=\"#collapse-5\" aria-expanded=\"false\" aria-controls=\"collapse-5\">\n                                <span class=\"d-inline-block\" style=\"padding-right:16px;\">\n                                    Affichages sur les v\u00e9hicules et transports en commun                                 <\/span>\n                            <\/button>\n                        <\/h3>\n                        <div id=\"collapse-5\" class=\"accordion-collapse collapse\" aria-labelledby=\"heading-5\" data-bs-parent=\"#services-home-accordion\">\n                            <div class=\"accordion-body ps-3 ms-1 ps-lg-0 ms-lg-0\">\n                                Transportez votre message sur la route avec les solutions d\u2019affichage dans les v\u00e9hicules et les transports en commun de DAC. Nous concevons et mettons en \u0153uvre des visuels accrocheurs qui transforment les bus, les trains et les flottes de camions en panneaux d\u2019affichage mobiles. Avec des d\u00e9cennies d\u2019exp\u00e9rience dans la publicit\u00e9 sur les transports en commun, nous savons comment maximiser l\u2019exposition et favoriser la notori\u00e9t\u00e9 de la marque dans les paysages urbains.                               <\/div>\n                        <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n\n    <\/div>\n<\/section>\n\n\n\n<section class=\"text-image-block  light_blue image-full- layout-one\">\n    <div class=\"container max-1448 padding60\">\n                \n        <div class=\"row image-left\">\n            <div class=\"col image-col\">\n                                            <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/iris-laptop.svg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/iris-laptop.svg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/iris-laptop.svg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/iris-laptop.svg\"\n                alt=\"Iris Laptop logo\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                        <\/div>\n            <div class=\"col text-col\">\n                <h3 class=\"w-100 text-wrap\">Bonjour, IRIS. Au revoir, les silos.<\/h3>                <p><p>Les m\u00e9dias traditionnels ne devraient pas \u00eatre s\u00e9par\u00e9s des autres efforts de marketing. Avec IRIS, notre plateforme int\u00e9gr\u00e9e, vous pouvez synchroniser lesdonn\u00e9es et les informations provenant d\u2019une multitude de canaux, en ligne et hors ligne, pour prendre des d\u00e9cisions commerciales\u00e9clair\u00e9es.<\/p><\/p>\n\n                                    <a href=\"https:\/\/www.dacgroup.com\/fr\/tech-platforms\/iris\/\" class=\"btn_primary-filled_black_arrow\" target=\"_self\">\n                        <div>EXPLOREZ IRIS<\/div>\n                        <svg width=\"24\" height=\"16\" viewBox=\"0 0 24 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"#171616\"><\/path>\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"><\/path>\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"><\/path>\n                        <\/svg>\n                    <\/a>\n                \n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n    <style>\n        :root {\n            --dots-color: #00aae7;\n        }\n\n        .services-carousel__title strong,\n        [data-theme=\"dark\"] [data-id=\"6a04f6908adc6\"]\n        {\n            color:#00aae7 !important;\n        }\n    <\/style>\n    \n\n\n<section id=\"services-carousel\" class=\"\">\n\n    <div class=\"services-carousel  light_blue small\">\n\n        <div class=\"container wrapper max-1448 padding60\">\n            \n            <div class=\"d-flex flex-column text-container\">\n                                    <h2 class=\"services-carousel__title  \">\n                        Technologie propri\u00e9taire con\u00e7ue pour obtenir des r\u00e9sultats impressionnants                     <\/h2>\n                    \n\n                \n                            <\/div>\n\n            <div class=\"services-carousel__items carousel\" data-theme=\"blue\">\n\n                <div class=\"carousel-wrapper owl-carousel owl-theme\">\n                                                                        <div class=\"services-carousel__item item\">\n                                                                    <div class=\"services-carousel__image\" >\n                                                <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-totalserp.svg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-totalserp.svg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-totalserp.svg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-totalserp.svg\"\n                alt=\"Total SERP logo\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                                <\/div>\n                                                                <h3  class=\"services-carousel__item-title visually-hidden\" data-id=\"6a04f6908adc6\" style=\"text-align: left\">TotalSERP<\/h3>\n                                <p class=\"services-carousel__item-description\" style=\"text-align: left\">Orchestrez des strat\u00e9gies de recherche coh\u00e9rentes pour dominer les r\u00e9sultats payants, organiques et locaux. <\/p>\n                            <\/div>\n                                                    <div class=\"services-carousel__item item\">\n                                                                    <div class=\"services-carousel__image\" >\n                                                <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-motive.svg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-motive.svg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-motive.svg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-motive.svg\"\n                alt=\"Motive logo\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                                <\/div>\n                                                                <h3  class=\"services-carousel__item-title visually-hidden\" data-id=\"6a04f6908adc6\" style=\"text-align: left\">Motive<\/h3>\n                                <p class=\"services-carousel__item-description\" style=\"text-align: left\">Prenez le contr\u00f4le de vos m\u00e9dias avec des informations, une planification, une activation et des rapports ax\u00e9s sur l\u2019audience. <\/p>\n                            <\/div>\n                                                    <div class=\"services-carousel__item item\">\n                                                                    <div class=\"services-carousel__image\" >\n                                                <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-gaurdrail.svg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-gaurdrail.svg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-gaurdrail.svg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-gaurdrail.svg\"\n                alt=\"gaurdrail\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                                <\/div>\n                                                                <h3  class=\"services-carousel__item-title visually-hidden\" data-id=\"6a04f6908adc6\" style=\"text-align: left\">Guardrail<\/h3>\n                                <p class=\"services-carousel__item-description\" style=\"text-align: left\">Boostez la productivit\u00e9 de l&#8217;IA en simplifiant les interactions et en maximisant l&#8217;efficacit\u00e9. <\/p>\n                            <\/div>\n                                                    <div class=\"services-carousel__item item\">\n                                                                    <div class=\"services-carousel__image\" >\n                                                <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-highlander.svg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-highlander.svg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-highlander.svg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/08\/logo-tech-highlander.svg\"\n                alt=\"highlander\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                                <\/div>\n                                                                <h3  class=\"services-carousel__item-title visually-hidden\" data-id=\"6a04f6908adc6\" style=\"text-align: left\">Highlander<\/h3>\n                                <p class=\"services-carousel__item-description\" style=\"text-align: left\">Optimisez\u202fla cr\u00e9ation de rapports et l&#8217;analyse pour am\u00e9liorer la prise de d\u00e9cision \u00e0 travers tous les canaux marketing. <\/p>\n                            <\/div>\n                                                            <\/div>\n\n            <\/div>\n\n                            <div class=\"services-carousel__cta\">\n                    <a href=\"https:\/\/www.dacgroup.com\/fr\/plates-formes-technologiques\/\" class=\"btn_primary-filled_black_arrow\" target=\"_self\">\n                        <div>EXPLOREZ NOS TECHNOLOGIES<\/div>\n                        <svg width=\"24\" height=\"16\" viewBox=\"0 0 24 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"#171616\"><\/path>\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"><\/path>\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"><\/path>\n                        <\/svg>\n                    <\/a>\n                <\/div>\n                    <\/div>\n\n    <\/div>\n\n<\/section>\n\n\n\n<section id=\"services\" class=\"text-services\">\n\n    <div class=\"container max-1448 padding60\">\n\n        \n                <div class=\"left-column\">\n\n                    <h2>Une int\u00e9gration transparente pour plus d&#8217;impact  <\/h2>\n        \n                    <p>Les m\u00e9dias traditionnels peuvent \u00eatre d\u00e9ploy\u00e9s en tant que solution autonome. Mais vous pouvez obtenir des r\u00e9sultats beaucoup plus \u00e9lev\u00e9s lorsque vous int\u00e9grez des tactiques hors ligne dans une strat\u00e9gie plus large et compl\u00e8te, quelque chose que DAC a la capacit\u00e9 unique de fournir \u00e0 grande \u00e9chelle. <\/p>\n            <\/div>\n    \n        \n        <div class=\"right-column\">\n\n                            <h3>OFFRES COMPL\u00c9MENTAIRES<\/h3>\n            \n            \n                <div class=\"services-accordion\" id=\"services-list-accordion\">\n\n                    \n                    <div class=\"service-item full_funnel_media\">\n\n                                                <div class=\"service-header\">\n                        \n                            \n                            <h3 class=\"service-title\">\n                                                                    <a\n                                        href=\"https:\/\/www.dacgroup.com\/fr\/services\/medias-digitaux\/\"\n                                        class=\"position-relative d-inline-flex full_funnel_media\"\n                                        target=\"_self\"\n                                    >M\u00e9dias Digitaux <\/a>\n                                                            <\/h3>\n\n                            \n                        <\/div>\n                        \n                    <\/div>\n\n                    \n                    <div class=\"service-item creative\">\n\n                                                <div class=\"service-header\">\n                        \n                            \n                            <h3 class=\"service-title\">\n                                                                    <a\n                                        href=\"https:\/\/www.dacgroup.com\/fr\/services\/ideation-creative\/\"\n                                        class=\"position-relative d-inline-flex creative\"\n                                        target=\"_self\"\n                                    >Id\u00e9ation cr\u00e9ative <\/a>\n                                                            <\/h3>\n\n                            \n                        <\/div>\n                        \n                    <\/div>\n\n                    \n                    <div class=\"service-item strategy\">\n\n                                                <div class=\"service-header\">\n                        \n                            \n                            <h3 class=\"service-title\">\n                                                                    <a\n                                        href=\"https:\/\/www.dacgroup.com\/fr\/services\/apercu-strategique-de-laudience-et-du-marche\/\"\n                                        class=\"position-relative d-inline-flex strategy\"\n                                        target=\"_self\"\n                                    >Analyse de l&#039;audience <\/a>\n                                                            <\/h3>\n\n                            \n                        <\/div>\n                        \n                    <\/div>\n\n                    \n                <\/div>\n\n            \n                            <a\n                    href=\"https:\/\/www.dacgroup.com\/fr\/services\/\"\n                    class=\"btn_primary-filled_white_hand\"\n                    target=\"\"\n                >\n                    <div>VOIR TOUS LES SERVICES<\/div>\n                    <svg width=\"24\" height=\"16\" viewBox=\"0 0 24 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n    <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"currentColor\"\/>\n    <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"\/>\n    <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"currentColor\"\/>\n<\/svg>                <\/a>\n            \n        <\/div>\n\n    <\/div>\n\n<\/section>\n\n\n\n<section class=\"text-image-block  light_grey image-full- layout-two\">\n    <div class=\"container max-1448 padding60\">\n                    <h2 class=\"block-heading\">Les m\u00e9dias traditionnels en action  <\/h2>\n                \n        <div class=\"row image-left\">\n            <div class=\"col image-col\">\n                                            <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2025\/01\/Blog-articles-Banners-2-1.png\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2025\/01\/Blog-articles-Banners-2-1.png\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2025\/01\/Blog-articles-Banners-2-1-768x384.png\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2025\/01\/Blog-articles-Banners-2-1-480x240.png\"\n                alt=\"\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                        <\/div>\n            <div class=\"col text-col\">\n                <h3 class=\"w-100 text-wrap\">10 cl\u00e9s incontournables pour r\u00e9ussir vos campagnes m\u00e9dia pendant les f\u00eates 2024<\/h3>                <p><p>Des id\u00e9es cl\u00e9s pour booster votre strat\u00e9gie m\u00e9dia des f\u00eates 2024. Entre personnalisation gr\u00e2ce \u00e0 l\u2019IA et optimisation budg\u00e9taire, gardez une longueur d\u2019avance en pleine saison de comp\u00e9tition.<\/p><\/p>\n\n                                    <a href=\"https:\/\/www.dacgroup.com\/fr\/insights\/blog\/paid-media\/10-cles-incontournables-pour-reussir-vos-campagnes-media-pendant-les-fetes-2024\/\" class=\"btn_primary-filled_black_arrow\" target=\"_blank\">\n                        <div>LIRE L&#039;ARTICLE<\/div>\n                        <svg width=\"24\" height=\"16\" viewBox=\"0 0 24 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"#171616\"><\/path>\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"><\/path>\n                            <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"><\/path>\n                        <\/svg>\n                    <\/a>\n                \n                            <\/div>\n        <\/div>\n    <\/div>\n<\/section>\n\n<section class=\"featured-articles-block layout-2\">\n    <div class=\"container\">\n    <h2><\/h2>        <div class=\"featured-articles-grid\">\n                            \n                                            <div class=\"featured-article\">\n                                                            <div class=\"featured-article-image\">\n                                            <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/12\/Banner-OOH-Blog-article.png\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/12\/Banner-OOH-Blog-article.png\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/12\/Banner-OOH-Blog-article-768x384.png\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/12\/Banner-OOH-Blog-article-480x240.png\"\n                alt=\"Affichage publicitaire ext\u00e9rieur : la combinaison gagnante du traditionnel statique (OOH) et du digital dynamique (DOOH)\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                            <\/div>\n                                                        <div class=\"featured-article-content\">\n                                                                    <a href=\"https:\/\/www.dacgroup.com\/fr\/insights\/blog\/strategy\/affichage-publicitaire-exterieur-la-combinaison-gagnante-du-traditionnel-statique-ooh-et-du-digital-dynamique-dooh\/\"\n                                       target=\"_blank\">\n                                        <h3 class=\"ps-4 ps-lg-0\">Affichage publicitaire ext\u00e9rieur : la combinaison gagnante du traditionnel statique (OOH) et du digital dynamique (DOOH)<\/h3>\n                                    <\/a>\n                                                            <\/div>\n                        <\/div>\n                                    \n                                            <div class=\"featured-article\">\n                                                            <div class=\"featured-article-image\">\n                                            <picture>\n                                <source\n                        media=\"(min-width: 1440px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/omnichannel-index.jpg\">\n            \n                                <source\n                        media=\"(min-width: 1024px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/omnichannel-index.jpg\">\n            \n                                <source\n                        media=\"(min-width: 768px)\"\n                        srcset=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/omnichannel-index.jpg\">\n            \n            <img decoding=\"async\"\n                src=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/omnichannel-index.jpg\"\n                alt=\"Physique, num\u00e9rique, national, local : comment prosp\u00e9rer dans l&#039;omnicanal ?\"\n                 loading=\"lazy\" \/>\n        <\/picture>\n                                            <\/div>\n                                                        <div class=\"featured-article-content\">\n                                                                    <a href=\"https:\/\/info.dacgroup.com\/dac-forrester-omnichannel-report-2021-fr\"\n                                       target=\"_self\">\n                                        <h3 class=\"ps-4 ps-lg-0\">Physique, num\u00e9rique, national, local : comment prosp\u00e9rer dans l&#039;omnicanal ?<\/h3>\n                                    <\/a>\n                                                            <\/div>\n                        <\/div>\n                                    \n                                    \n                                                        <\/div>\n    <\/div>\n<\/section>\n\n\n\n<section class=\"phrase-carousel\" data-carousel=\"enable\" data-ptd=\"140\" data-pbd=\"140\" data-ptm=\"35\" data-pbm=\"35\" >\n    \n    \n    <button id=\"play-pause-button\"><img decoding=\"async\" src=\"\/wp-content\/themes\/dac\/img\/icons\/stop-black.svg\" alt=\"Control Button\"><\/button>\n\n    \n    <div class=\"container max-1448 padding60\">\n\n        <h2 style=\"color:#363534\">\n\n            \n                \n                <div class=\"scroller\">\n                    <div class=\"inner\">\n                    \n                                                                         \n                            <div class=\"phrase\" data-bgcolor=\"#C7F2B3\">Amplifiez votre port\u00e9e via un m\u00e9dia plus efficace.<\/div>\n\n                         \n                            <div class=\"phrase\" data-bgcolor=\"#FCD48D\">Attirez plus de clients avec une strat\u00e9gie locale.<\/div>\n\n                         \n                            <div class=\"phrase\" data-bgcolor=\"#ACD8F3\">Faites des choix plus \u00e9clair\u00e9s gr\u00e2ce \u00e0 la mesure.<\/div>\n\n                         \n                            <div class=\"phrase\" data-bgcolor=\"#fabfbf\">Obtenez plus de succ\u00e8s en visant la performance.<\/div>\n\n                         \n                            <div class=\"phrase\" data-bgcolor=\"#C7F2B3\">Prenez plus\u00a0d\u2019avance avec les bonnes solutions IA.<\/div>\n\n                         \n                            <div class=\"phrase\" data-bgcolor=\"#FCD48D\">Gagnez en visibilit\u00e9 avec une marque plus forte.<\/div>\n\n                        \n                    <\/div>\n                <\/div>\n\n                \n                                    \n        <\/h2>\n                    \n        \n                    \n<div class=\"  \">\n\n        <a href=\"https:\/\/www.dacgroup.com\/fr\/contactez-nous\/\" class=\"btn_primary-filled_black_arrow\" >\n    \n        <div>Allons de l&#8217;avant<\/div>\n\n        \n            \n            <svg width=\"24\" height=\"16\" viewBox=\"0 0 24 16\" fill=\"none\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\">\n                <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"#171616\"\/>\n                <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"\/>\n                <path d=\"M19.7303 8.96285L14.8759 14.2138C14.5429 14.5741 14.5429 15.1299 14.876 15.4901C15.2481 15.8925 15.8842 15.8925 16.2563 15.49L23.1809 8L16.2563 0.509971C15.8842 0.107507 15.2481 0.10747 14.876 0.509891C14.5429 0.870102 14.5429 1.42591 14.8759 1.78616L19.7303 7.03692H0.962963C0.431133 7.03692 0 7.46806 0 7.99988C0 8.53171 0.431133 8.96285 0.962963 8.96285H19.7303Z\" fill=\"black\" fill-opacity=\"0.2\"\/>\n            <\/svg>\n\n            \n\n        \n        <\/a>\n    \n<\/div>\n\n\n    <\/div>\n<\/section>","protected":false},"featured_media":949,"parent":92678,"menu_order":0,"template":"","meta":{"content-type":""},"class_list":["post-1454","services","type-services","status-publish","has-post-thumbnail","hentry"],"acf":{"tracking_category":"Paid media"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.7 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>M\u00e9dias traditionnels | DAC<\/title>\n<meta name=\"description\" content=\"Les solutions de m\u00e9dias traditionnels de DAC vous permettent d&#039;atteindre le bon public, au bon moment et dans le bon format, dans le cadre d&#039;un mod\u00e8le de communication un \u00e0 plusieurs.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e9dias traditionnels | DAC\" \/>\n<meta property=\"og:description\" content=\"Les solutions de m\u00e9dias traditionnels de DAC vous permettent d&#039;atteindre le bon public, au bon moment et dans le bon format, dans le cadre d&#039;un mod\u00e8le de communication un \u00e0 plusieurs.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/\" \/>\n<meta property=\"og:site_name\" content=\"DAC\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/DACGroup\" \/>\n<meta property=\"article:modified_time\" content=\"2026-02-10T17:25:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"470\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/DAC-logo.svg\" \/>\n<meta name=\"twitter:site\" content=\"@DAC_group\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/\",\"url\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/\",\"name\":\"M\u00e9dias traditionnels | DAC\",\"isPartOf\":{\"@id\":\"https:\/\/www.dacgroup.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg\",\"datePublished\":\"2024-08-22T22:20:19+00:00\",\"dateModified\":\"2026-02-10T17:25:51+00:00\",\"description\":\"Les solutions de m\u00e9dias traditionnels de DAC vous permettent d'atteindre le bon public, au bon moment et dans le bon format, dans le cadre d'un mod\u00e8le de communication un \u00e0 plusieurs.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#primaryimage\",\"url\":\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg\",\"contentUrl\":\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg\",\"width\":600,\"height\":470,\"caption\":\"Abstrakte Darstellung von bunten Lichtpunkten auf dunklem Hintergrund, die einen tunnelartigen Effekt erzeugen.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.dacgroup.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Cat\u00e9gorie M\u00e9dias payants\",\"item\":\"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"M\u00e9dias traditionnels\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.dacgroup.com\/fr\/#website\",\"url\":\"https:\/\/www.dacgroup.com\/fr\/\",\"name\":\"DAC group\",\"description\":\"DAC\",\"publisher\":{\"@id\":\"https:\/\/www.dacgroup.com\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.dacgroup.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.dacgroup.com\/fr\/#organization\",\"name\":\"DAC group\",\"alternateName\":\"DAC\",\"url\":\"https:\/\/www.dacgroup.com\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.dacgroup.com\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/DAC-logo.svg\",\"contentUrl\":\"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/DAC-logo.svg\",\"caption\":\"DAC group\"},\"image\":{\"@id\":\"https:\/\/www.dacgroup.com\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/DACGroup\",\"https:\/\/x.com\/DAC_group\",\"https:\/\/www.linkedin.com\/company\/dac-group\/\",\"https:\/\/www.instagram.com\/dac_group\/\",\"https:\/\/www.youtube.com\/user\/DACgroup1976\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e9dias traditionnels | DAC","description":"Les solutions de m\u00e9dias traditionnels de DAC vous permettent d'atteindre le bon public, au bon moment et dans le bon format, dans le cadre d'un mod\u00e8le de communication un \u00e0 plusieurs.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/","og_locale":"fr_FR","og_type":"article","og_title":"M\u00e9dias traditionnels | DAC","og_description":"Les solutions de m\u00e9dias traditionnels de DAC vous permettent d'atteindre le bon public, au bon moment et dans le bon format, dans le cadre d'un mod\u00e8le de communication un \u00e0 plusieurs.","og_url":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/","og_site_name":"DAC","article_publisher":"https:\/\/www.facebook.com\/DACGroup","article_modified_time":"2026-02-10T17:25:51+00:00","og_image":[{"width":600,"height":470,"url":"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/DAC-logo.svg","twitter_site":"@DAC_group","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/","url":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/","name":"M\u00e9dias traditionnels | DAC","isPartOf":{"@id":"https:\/\/www.dacgroup.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#primaryimage"},"image":{"@id":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#primaryimage"},"thumbnailUrl":"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg","datePublished":"2024-08-22T22:20:19+00:00","dateModified":"2026-02-10T17:25:51+00:00","description":"Les solutions de m\u00e9dias traditionnels de DAC vous permettent d'atteindre le bon public, au bon moment et dans le bon format, dans le cadre d'un mod\u00e8le de communication un \u00e0 plusieurs.","breadcrumb":{"@id":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#primaryimage","url":"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg","contentUrl":"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/06\/paid-media-1.jpg","width":600,"height":470,"caption":"Abstrakte Darstellung von bunten Lichtpunkten auf dunklem Hintergrund, die einen tunnelartigen Effekt erzeugen."},{"@type":"BreadcrumbList","@id":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/medias-traditionnels\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.dacgroup.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Cat\u00e9gorie M\u00e9dias payants","item":"https:\/\/www.dacgroup.com\/fr\/services\/paid-media\/"},{"@type":"ListItem","position":3,"name":"M\u00e9dias traditionnels"}]},{"@type":"WebSite","@id":"https:\/\/www.dacgroup.com\/fr\/#website","url":"https:\/\/www.dacgroup.com\/fr\/","name":"DAC group","description":"DAC","publisher":{"@id":"https:\/\/www.dacgroup.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.dacgroup.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.dacgroup.com\/fr\/#organization","name":"DAC group","alternateName":"DAC","url":"https:\/\/www.dacgroup.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.dacgroup.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/DAC-logo.svg","contentUrl":"https:\/\/www.dacgroup.com\/wp-content\/uploads\/2024\/09\/DAC-logo.svg","caption":"DAC group"},"image":{"@id":"https:\/\/www.dacgroup.com\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/DACGroup","https:\/\/x.com\/DAC_group","https:\/\/www.linkedin.com\/company\/dac-group\/","https:\/\/www.instagram.com\/dac_group\/","https:\/\/www.youtube.com\/user\/DACgroup1976"]}]}},"_links":{"self":[{"href":"https:\/\/www.dacgroup.com\/fr\/wp-json\/wp\/v2\/services\/1454","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.dacgroup.com\/fr\/wp-json\/wp\/v2\/services"}],"about":[{"href":"https:\/\/www.dacgroup.com\/fr\/wp-json\/wp\/v2\/types\/services"}],"up":[{"embeddable":true,"href":"https:\/\/www.dacgroup.com\/fr\/wp-json\/wp\/v2\/services\/92678"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.dacgroup.com\/fr\/wp-json\/wp\/v2\/media\/949"}],"wp:attachment":[{"href":"https:\/\/www.dacgroup.com\/fr\/wp-json\/wp\/v2\/media?parent=1454"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}